{"id":47935,"date":"2023-02-10T17:40:41","date_gmt":"2023-02-10T16:40:41","guid":{"rendered":"https:\/\/www.dolomitiprealpi.it\/santuario-della-madonna-di-caravaggio\/"},"modified":"2026-07-10T13:46:19","modified_gmt":"2026-07-10T11:46:19","slug":"santuario-della-madonna-di-caravaggio","status":"publish","type":"post","link":"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/","title":{"rendered":"Santuario della Madonna di Caravaggio"},"content":{"rendered":"<p>Die Kirche ist dem Heiligen Erl\u00f6ser gewidmet, ist aber auch das Heiligtum der Madonna von Caravaggio <\/p>\n<p><\/p>\n<p>Ged\u00e4chtnis der Madonna von Caravaggio: 26. Mai<\/p>\n<p>Ged\u00e4chtnis des Hl. Erl\u00f6sers: 6. August<\/p>\n<p>In Travagola wurde die Kirche um 1516 erbaut und im letzten Jahrhundert umgebaut. Sie beherbergt ein Gem\u00e4lde von Giovanni d\u2019Antona. Mit der Kapelle, die dem Kult der Madonna von Caravaggio gewidmet ist, bildet Travagola eines der bedeutendsten marianischen Zentren im Gebiet von Feltre und Belluno. Hier wird ein Gem\u00e4lde von Francesco Frigimelica zum Thema der Verkl\u00e4rung aufbewahrt. Die Pfarrei, die dem Hl. Erl\u00f6ser gewidmet ist, wurde 1950 gegr\u00fcndet.<\/p>\n<p>Auf dem Weg von Pedavena zum Canalet, wenn man den H\u00fcgel erreicht, der zum Platz von Travagola f\u00fchrt, erscheint in voller Aussicht, vom Sonnenlicht erleuchtet, die Kirche von Travagola, die wie gesagt im Jahr 1516 \u2013 also vor 500 Jahren \u2013 erbaut wurde. Es ist besonders eindrucksvoll, sie \u00fcber einen kurzen, mit B\u00e4umen ges\u00e4umten Torbogenweg zu erreichen, der sich in jeder Jahreszeit in seiner vollen Pracht zeigt. Eine niedrige Mauer umarmt die Kirche, die dem Hl. Erl\u00f6ser, dem Pfarrhaus und dem kleinen Denkmal f\u00fcr die Gefallenen gewidmet ist.<\/p>\n<p>Die Fassade, ein Werk des Marchioro, schlicht in den Linien, besteht aus vier Pilastern, die das dreieckige Gesims st\u00fctzen; zwischen den beiden mittleren Pilastern, die durch einen flachen Bogen verbunden sind, befindet sich der Haupteingang, der von dem Bischofswappen \u00fcberragt wird; h\u00f6her oben sind drei falsche Fenster, die mit einem Bogen abgeschlossen sind, und ein falsches Rosettenfenster im Innern des Dreiecks des Gesimses. Es gibt zwei Kapellen und seitliche T\u00fcren, und weiter hinten steht der Glockenturm.<\/p>\n<p>Das nicht sehr gro\u00dfe Innere besteht aus einem einzigen Schiff, das oben von einem flachen Gew\u00f6lbe geschlossen wird, von dem ein majest\u00e4tischer Kronleuchter h\u00e4ngt; auch das Taufbecken aus dem Jahr 1641 ist von Bedeutung. Architektonisch ist der Raum f\u00fcr die Gl\u00e4ubigen durch einen Triumphbogen getrennt, der Spuren von Freskod dekorationen bewahrt, wo man noch Teile des K\u00f6rpers des Hl. Sebastian, der von einem Pfeil getroffen wurde, erkennen kann, eine Malerei, die \u00e4lter ist als die dar\u00fcber liegenden Dekorationen. Der urspr\u00fcngliche Boden aus Steinplatten verbindet das Hauptschiff mit dem erh\u00f6hten Altarraum.<\/p>\n<p>Im Altarraum befindet sich der Hauptaltar mit zwei kostbaren bemalten Holzfiguren, die den Hl. Petrus und den Hl. Paulus darstellen und k\u00fcrzlich restauriert wurden. Korinthische S\u00e4ulen, die durch einen Bogen verbunden sind, leiten den Blick auf das Altarbild mit der Verkl\u00e4rung: Jesus 40 Tage vor der Kreuzigung zwischen Elia und Mose, das Gesetz und die Propheten, und unten die Apostel Petrus, Jakobus und Johannes. Die Figuren sind symmetrisch zur Figur Christi angeordnet und heben eine formale Strenge, verbunden mit einer klaren Kommunikation, hervor; die Gesichter der Figuren sind so realistisch behandelt, dass sie stark charakterisierte Portr\u00e4ts zu sein scheinen. Es ist ein wichtiges Werk, das Frigimelica zugeschrieben wird, einem Maler, der 1596 in Feltre aktiv war und eine Schl\u00fcsselrolle in der Erneuerung der Kunst in Belluno spielte.<\/p>\n<p>Die Kapelle des Hl. Antonius von Padua, links, hat eine besondere Geschichte. Im Sommer 1783 begann eine Rinderseuche in Pren und Villapaiera, und man vermutete, dass sie mit einigen Rindern aus dem Ausland importiert worden war. Sie traf dann Pedavena und die Sega. In Facen war die Situation besonders schlimm, sodass das Dorf von 20. Dezember bis 1. M\u00e4rz 1784 streng isoliert wurde. Mehr als 70 Tiere starben, die eine wichtige Ressource darstellten, und in diesem besonders schneereichen Winter kann man sich vorstellen, wie das Schicksal der armen Menschen war, die in Isolation lebten. Das Gesundheitsamt schickte 10 Soldaten aus Dalmatien, die von den \u00f6rtlichen Menschen finanziert wurden, um den strengen Bewegungsverbots durchzusetzen, sodass selbst der Pfarrer Facen nur im \u00e4u\u00dfersten Notfall betreten durfte.<\/p>\n<p>Travagola und Umgebung wurden nicht getroffen. Um f\u00fcr die \u00fcberstandene Gefahr zu danken, beschlossen die Gemeindemitglieder, einen neuen Altar zu errichten, der sich links im Schiff befindet, dem Hl. Antonius von Padua gewidmet, und beauftragten Giovanni D\u2019Antona ein \u00d6lbild als Ex-Voto zu schaffen, also aufgrund eines Gel\u00fcbdes.<\/p>\n<p>Der fertiggestellte Altar wurde 1789 geweiht.<\/p>\n<p>Die andere Kapelle, die der Madonna von Caravaggio gewidmet ist, stammt von 1894.<\/p>\n<p>Fr\u00fchere Erscheinungen der Jungfrau in Caravaggio (Bergamo) und in Pin\u00e8 (Pergine Valsugana-Trento), die Orte von Wallfahrten waren, \u00fcberzeugten die Leute, auch in Travagola ein marianisches Heiligtum zu er\u00f6ffnen, das im Laufe der Zeit ein Ziel der Verehrung geworden ist.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Kirche ist dem Heiligen Erl\u00f6ser gewidmet, ist aber auch das Heiligtum der Madonna von Caravaggio Ged\u00e4chtnis der Madonna von Caravaggio: 26. Mai Ged\u00e4chtnis des Hl. Erl\u00f6sers: 6. August In<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[350,1],"tags":[285,122,234,286,287,121],"class_list":["post-47935","post","type-post","status-publish","format-standard","hentry","category-kirchen-und-heilige-orte","category-uncategorized","tag-feratel-sync-de","tag-feratel-sync","tag-poi","tag-poi-de","tag-punti-interesse-feratel-de","tag-punti-interesse-feratel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Santuario della Madonna di Caravaggio - Dolomiti Prealpi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santuario della Madonna di Caravaggio - Dolomiti Prealpi\" \/>\n<meta property=\"og:description\" content=\"Die Kirche ist dem Heiligen Erl\u00f6ser gewidmet, ist aber auch das Heiligtum der Madonna von Caravaggio Ged\u00e4chtnis der Madonna von Caravaggio: 26. Mai Ged\u00e4chtnis des Hl. Erl\u00f6sers: 6. August In\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/\" \/>\n<meta property=\"og:site_name\" content=\"Dolomiti Prealpi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dolomitiprealpi.it\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-10T16:40:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T11:46:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dolomitiprealpi.it\/wp-content\/uploads\/2022\/11\/C.-Timpone-Foto-archivio-Consorzio-turistico-Dolomiti-Prealpi-Nevegal-Belluno-Bike-18-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1888\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mapo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mapo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/\"},\"author\":{\"name\":\"Mapo\",\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/#\/schema\/person\/3442beb0554060944b4326d8211c9c04\"},\"headline\":\"Santuario della Madonna di Caravaggio\",\"datePublished\":\"2023-02-10T16:40:41+00:00\",\"dateModified\":\"2026-07-10T11:46:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/\"},\"wordCount\":734,\"publisher\":{\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/#organization\"},\"keywords\":[\"Feratel sync\",\"Feratel sync\",\"POI\",\"POI\",\"Punti interesse Feratel\",\"Punti interesse Feratel\"],\"articleSection\":[\"Kirchen und Heilige Orte\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/\",\"url\":\"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/\",\"name\":\"Santuario della Madonna di Caravaggio - Dolomiti Prealpi\",\"isPartOf\":{\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/#website\"},\"datePublished\":\"2023-02-10T16:40:41+00:00\",\"dateModified\":\"2026-07-10T11:46:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dolomitiprealpi.it\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santuario della Madonna di Caravaggio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/#website\",\"url\":\"https:\/\/www.dolomitiprealpi.it\/de\/\",\"name\":\"Dolomiti Prealpi\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dolomitiprealpi.it\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/#organization\",\"name\":\"Consorzio Dolomiti Prealpi\",\"url\":\"https:\/\/www.dolomitiprealpi.it\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dolomitiprealpi.it\/wp-content\/uploads\/2023\/03\/dolomitiprealpi-favicon.jpg\",\"contentUrl\":\"https:\/\/www.dolomitiprealpi.it\/wp-content\/uploads\/2023\/03\/dolomitiprealpi-favicon.jpg\",\"width\":512,\"height\":512,\"caption\":\"Consorzio Dolomiti Prealpi\"},\"image\":{\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dolomitiprealpi.it\/\",\"https:\/\/www.instagram.com\/dolomitiprealpi\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/#\/schema\/person\/3442beb0554060944b4326d8211c9c04\",\"name\":\"Mapo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.dolomitiprealpi.it\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7ce219f4d7d86c45bf979b9d8e0150ad0a4bbd7d3fa61bcb36ffa3cb99018dda?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7ce219f4d7d86c45bf979b9d8e0150ad0a4bbd7d3fa61bcb36ffa3cb99018dda?s=96&d=mm&r=g\",\"caption\":\"Mapo\"},\"url\":\"https:\/\/www.dolomitiprealpi.it\/de\/author\/mapo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santuario della Madonna di Caravaggio - Dolomiti Prealpi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/","og_locale":"de_DE","og_type":"article","og_title":"Santuario della Madonna di Caravaggio - Dolomiti Prealpi","og_description":"Die Kirche ist dem Heiligen Erl\u00f6ser gewidmet, ist aber auch das Heiligtum der Madonna von Caravaggio Ged\u00e4chtnis der Madonna von Caravaggio: 26. Mai Ged\u00e4chtnis des Hl. Erl\u00f6sers: 6. August In","og_url":"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/","og_site_name":"Dolomiti Prealpi","article_publisher":"https:\/\/www.facebook.com\/dolomitiprealpi.it\/","article_published_time":"2023-02-10T16:40:41+00:00","article_modified_time":"2026-07-10T11:46:19+00:00","og_image":[{"width":2048,"height":1888,"url":"https:\/\/www.dolomitiprealpi.it\/wp-content\/uploads\/2022\/11\/C.-Timpone-Foto-archivio-Consorzio-turistico-Dolomiti-Prealpi-Nevegal-Belluno-Bike-18-2.jpg","type":"image\/jpeg"}],"author":"Mapo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Mapo","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/#article","isPartOf":{"@id":"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/"},"author":{"name":"Mapo","@id":"https:\/\/www.dolomitiprealpi.it\/de\/#\/schema\/person\/3442beb0554060944b4326d8211c9c04"},"headline":"Santuario della Madonna di Caravaggio","datePublished":"2023-02-10T16:40:41+00:00","dateModified":"2026-07-10T11:46:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/"},"wordCount":734,"publisher":{"@id":"https:\/\/www.dolomitiprealpi.it\/de\/#organization"},"keywords":["Feratel sync","Feratel sync","POI","POI","Punti interesse Feratel","Punti interesse Feratel"],"articleSection":["Kirchen und Heilige Orte"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/","url":"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/","name":"Santuario della Madonna di Caravaggio - Dolomiti Prealpi","isPartOf":{"@id":"https:\/\/www.dolomitiprealpi.it\/de\/#website"},"datePublished":"2023-02-10T16:40:41+00:00","dateModified":"2026-07-10T11:46:19+00:00","breadcrumb":{"@id":"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dolomitiprealpi.it\/de\/santuario-della-madonna-di-caravaggio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dolomitiprealpi.it\/de\/"},{"@type":"ListItem","position":2,"name":"Santuario della Madonna di Caravaggio"}]},{"@type":"WebSite","@id":"https:\/\/www.dolomitiprealpi.it\/de\/#website","url":"https:\/\/www.dolomitiprealpi.it\/de\/","name":"Dolomiti Prealpi","description":"","publisher":{"@id":"https:\/\/www.dolomitiprealpi.it\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dolomitiprealpi.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.dolomitiprealpi.it\/de\/#organization","name":"Consorzio Dolomiti Prealpi","url":"https:\/\/www.dolomitiprealpi.it\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.dolomitiprealpi.it\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.dolomitiprealpi.it\/wp-content\/uploads\/2023\/03\/dolomitiprealpi-favicon.jpg","contentUrl":"https:\/\/www.dolomitiprealpi.it\/wp-content\/uploads\/2023\/03\/dolomitiprealpi-favicon.jpg","width":512,"height":512,"caption":"Consorzio Dolomiti Prealpi"},"image":{"@id":"https:\/\/www.dolomitiprealpi.it\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dolomitiprealpi.it\/","https:\/\/www.instagram.com\/dolomitiprealpi\/"]},{"@type":"Person","@id":"https:\/\/www.dolomitiprealpi.it\/de\/#\/schema\/person\/3442beb0554060944b4326d8211c9c04","name":"Mapo","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.dolomitiprealpi.it\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7ce219f4d7d86c45bf979b9d8e0150ad0a4bbd7d3fa61bcb36ffa3cb99018dda?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ce219f4d7d86c45bf979b9d8e0150ad0a4bbd7d3fa61bcb36ffa3cb99018dda?s=96&d=mm&r=g","caption":"Mapo"},"url":"https:\/\/www.dolomitiprealpi.it\/de\/author\/mapo\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.dolomitiprealpi.it\/de\/wp-json\/wp\/v2\/posts\/47935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dolomitiprealpi.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dolomitiprealpi.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dolomitiprealpi.it\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dolomitiprealpi.it\/de\/wp-json\/wp\/v2\/comments?post=47935"}],"version-history":[{"count":1,"href":"https:\/\/www.dolomitiprealpi.it\/de\/wp-json\/wp\/v2\/posts\/47935\/revisions"}],"predecessor-version":[{"id":50291,"href":"https:\/\/www.dolomitiprealpi.it\/de\/wp-json\/wp\/v2\/posts\/47935\/revisions\/50291"}],"wp:attachment":[{"href":"https:\/\/www.dolomitiprealpi.it\/de\/wp-json\/wp\/v2\/media?parent=47935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dolomitiprealpi.it\/de\/wp-json\/wp\/v2\/categories?post=47935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dolomitiprealpi.it\/de\/wp-json\/wp\/v2\/tags?post=47935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}